{"id":98476,"date":"2022-11-07T01:49:46","date_gmt":"2022-11-07T00:49:46","guid":{"rendered":"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg"},"modified":"2022-11-07T01:49:46","modified_gmt":"2022-11-07T00:49:46","slug":"sublimes-tresses-africaines","status":"inherit","type":"attachment","link":"https:\/\/flashmode.tn\/magazine\/__trashed-17\/sublimes-tresses-africaines\/","title":{"rendered":"Sublimes-tresses-africaines"},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"tdm_status":"","tdm_grid_status":""},"class_list":["post-98476","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v25.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sublimes-tresses-africaines - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sublimes-tresses-africaines - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/flashmode.magazine\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?fit=300%2C274&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@agenceflashmode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg\",\"url\":\"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg\",\"name\":\"Sublimes-tresses-africaines - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\",\"isPartOf\":{\"@id\":\"https:\/\/flashmode.tn\/magazine\/#website\"},\"datePublished\":\"2022-11-07T00:49:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/flashmode.tn\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top : Des Belles Mod\u00e8les Tresse Coll\u00e9e Africaine Tendance 2022\",\"item\":\"https:\/\/flashmode.tn\/magazine\/__trashed-17\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sublimes-tresses-africaines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/#website\",\"url\":\"https:\/\/flashmode.tn\/magazine\/\",\"name\":\"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\",\"description\":\"Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb, cr\u00e9\u00e9 pour les hommes et les femmes : conseils beaut\u00e9, mode femme, mode homme, recettes de cuisine, c\u00e9l\u00e9brit\u00e9s et people, mannequins et top modeles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flashmode.tn\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sublimes-tresses-africaines - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg","og_locale":"fr_FR","og_type":"article","og_title":"Sublimes-tresses-africaines - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","og_url":"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg","og_site_name":"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","article_publisher":"https:\/\/www.facebook.com\/flashmode.magazine\/","og_image":[{"width":300,"height":274,"url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?fit=300%2C274&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@agenceflashmode","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg","url":"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg","name":"Sublimes-tresses-africaines - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","isPartOf":{"@id":"https:\/\/flashmode.tn\/magazine\/#website"},"datePublished":"2022-11-07T00:49:46+00:00","breadcrumb":{"@id":"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/flashmode.tn\/magazine\/"},{"@type":"ListItem","position":2,"name":"Top : Des Belles Mod\u00e8les Tresse Coll\u00e9e Africaine Tendance 2022","item":"https:\/\/flashmode.tn\/magazine\/__trashed-17\/"},{"@type":"ListItem","position":3,"name":"Sublimes-tresses-africaines"}]},{"@type":"WebSite","@id":"https:\/\/flashmode.tn\/magazine\/#website","url":"https:\/\/flashmode.tn\/magazine\/","name":"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","description":"Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb, cr\u00e9\u00e9 pour les hommes et les femmes : conseils beaut\u00e9, mode femme, mode homme, recettes de cuisine, c\u00e9l\u00e9brit\u00e9s et people, mannequins et top modeles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flashmode.tn\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_shortlink":"https:\/\/wp.me\/a8BPGr-pCk","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"274\" src=\"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?fit=300%2C274&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":300,"height":274,"file":"2022\/11\/Sublimes-tresses-africaines.jpeg","sizes":{"thumbnail":{"file":"Sublimes-tresses-africaines-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=150%2C150&ssl=1"},"td_218x150":{"file":"Sublimes-tresses-africaines-218x150.jpeg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=218%2C150&ssl=1"},"td_80x60":{"file":"Sublimes-tresses-africaines-80x60.jpeg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=80%2C60&ssl=1"},"td_100x70":{"file":"Sublimes-tresses-africaines-100x70.jpeg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=100%2C70&ssl=1"},"td_265x198":{"file":"Sublimes-tresses-africaines-265x198.jpeg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=265%2C198&ssl=1"},"td_324x160":{"file":"Sublimes-tresses-africaines-300x160.jpeg","width":300,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=300%2C160&ssl=1"},"td_324x235":{"file":"Sublimes-tresses-africaines-300x235.jpeg","width":300,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=300%2C235&ssl=1"},"td_356x220":{"file":"Sublimes-tresses-africaines-300x220.jpeg","width":300,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=300%2C220&ssl=1"},"td_533x261":{"file":"Sublimes-tresses-africaines-300x261.jpeg","width":300,"height":261,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?resize=300%2C261&ssl=1"},"full":{"file":"Sublimes-tresses-africaines.jpeg?fit=300%2C274&ssl=1","width":300,"height":274,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg?fit=300%2C274&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":98110,"source_url":"https:\/\/flashmode.tn\/magazine\/wp-content\/uploads\/2022\/11\/Sublimes-tresses-africaines.jpeg","_links":{"self":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/media\/98476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/comments?post=98476"}]}}