{"id":47169,"date":"2021-11-23T04:20:32","date_gmt":"2021-11-23T03:20:32","guid":{"rendered":"https:\/\/flashmode.tn\/magazine\/?p=47169"},"modified":"2021-11-23T04:20:32","modified_gmt":"2021-11-23T03:20:32","slug":"quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3","status":"publish","type":"post","link":"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/","title":{"rendered":"Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ?"},"content":{"rendered":"<p>Le charbon de barbecue comme les m\u00e9gots de cigarettes, la poussi\u00e8re d&rsquo;aspirateur, les mat\u00e9riaux non biod\u00e9gradables, des <b>d\u00e9chets<\/b> d&rsquo;animaux, les graines et noyaux, les feuilles verniss\u00e9es (lierre, laurier), les lisserons et plantes rampantes, les plantes et v\u00e9g\u00e9taux trait\u00e9s r\u00e9sineux, <b>ne<\/b> peuvent <b>pas<\/b> \u00eatre mis dans le &#8230;<\/p>\n<p>Mais encore, Comment utiliser les pelures d&rsquo;agrumes ?<\/p>\n<p><b>  Que faire avec les \u00e9pluchures d&rsquo;  <b>   agrumes  <\/b>  ? <\/b> <\/p>\n<ol>\n<li>   De la poudre de zestes d&rsquo;   <b>    agrumes   <\/b>   \u2013 votre nouvelle \u00e9pice-phare.  <\/li>\n<li>   Des \u00e9corces d&rsquo;   <b>    agrumes   <\/b>   s\u00e9ch\u00e9es pour la d\u00e9co.  <\/li>\n<li>   Un sirop pour votre kombucha.  <\/li>\n<li>   Des orangettes ou des \u00e9corces d&rsquo;orange confites.  <\/li>\n<li>   De l&rsquo;eau aromatis\u00e9e.  <\/li>\n<li>   Des produits m\u00e9nagers.  <\/li>\n<li>   Un gommage pour la peau \u00e0 l&rsquo;orange.  <\/li>\n<\/ol>\n<p>et Quel fruit ne pas mettre dans le compost ?<\/p>\n<p><b>  \u00c0  <b>   ne pas mettre  <\/b>  : <\/b> <\/p>\n<ul>\n<li>   Les peaux d&rsquo;agrumes, trop longues \u00e0 se d\u00e9composer.  <\/li>\n<li>   La viande ou les produits laitiers.  <\/li>\n<li>   Les   <b>    fruits   <\/b>   \u00e0 coque (noix, noisette, amande), trop longs \u00e0 se d\u00e9composer sauf pour usage en paillage.  <\/li>\n<li>   Les noyaux (avocat&#8230;). Cela n&rsquo;a   <b>    pas   <\/b>   d&rsquo;int\u00e9r\u00eat, ils   <b>    ne   <\/b>   se d\u00e9composeront   <b>    pas   <\/b>   .  <\/li>\n<\/ul>\n<p>Quels l\u00e9gumes ne pas mettre au compost ?<\/p>\n<p><b>  Il est vivement d\u00e9conseill\u00e9 de  <b>   mettre  <\/b>  dans votre  <b>   compost  <\/b>  : <\/b> <\/p>\n<ul>\n<li>   des \u00e9pluchures de pomme de terre ou de poire, qui peuvent \u00eatre porteuses de maladies ;  <\/li>\n<li>   des plantes susceptibles de porter des maladies telles que les rosiers ou les arbres fruitiers ;  <\/li>\n<\/ul>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenus de la page<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Pourquoi_ne_pas_mettre_des_agrumes_dans_le_compost\" >Pourquoi ne pas mettre des agrumes dans le compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Comment_utiliser_les_epluchures_dorange\" >Comment utiliser les \u00e9pluchures d&rsquo;orange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Comment_conserver_la_peau_dorange\" >Comment conserver la peau d&rsquo;orange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Ou_jeter_les_epluchures_dorange\" >O\u00f9 jeter les \u00e9pluchures d&rsquo;orange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Quest-ce_qui_va_dans_le_compost\" >Qu&rsquo;est-ce qui va dans le compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Comment_reussir_son_compost_les_erreurs_a_eviter\" >Comment r\u00e9ussir son compost les erreurs \u00e0 \u00e9viter ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Est-ce_que_le_citron_va_au_compost\" >Est-ce que le citron va au compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Quel_dechet_pour_un_bon_compost\" >Quel d\u00e9chet pour un bon compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Pourquoi_pas_de_pain_dans_le_compost\" >Pourquoi pas de pain dans le compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Est-ce_quon_peut_mettre_du_pain_dans_le_compost\" >Est-ce qu&rsquo;on peut mettre du pain dans le compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Comment_faire_secher_peau_dorange\" >Comment faire s\u00e9cher peau d&rsquo;orange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Comment_secher_la_peau_dorange\" >Comment s\u00e9cher la peau d&rsquo;orange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Comment_faire_secher_la_peau_dorange\" >Comment faire s\u00e9cher la peau d&rsquo;orange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Comment_faire_secher_la_peau_dorange-2\" >Comment faire s\u00e9cher la peau d&rsquo;orange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Est-ce_que_la_peau_dune_orange_se_mange\" >Est-ce que la peau d&rsquo;une orange se mange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Comment_secher_la_peau_dorange-2\" >Comment s\u00e9cher la peau d&rsquo;orange ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Pourquoi_il_ne_faut_pas_mettre_dagrumes_dans_un_compost\" >Pourquoi il ne faut pas mettre d&rsquo;agrumes dans un compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Pourquoi_pas_de_pelures_dagrumes_dans_le_compost\" >Pourquoi pas de pelures d&rsquo;agrumes dans le compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Est-ce_que_la_viande_va_au_compost\" >Est-ce que la viande va au compost ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Quest-ce_qui_va_dans_le_bac_brun\" >Qu&rsquo;est-ce qui va dans le bac brun ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#Est-ce_que_les_noyaux_vont_au_compost\" >Est-ce que les noyaux vont au compost ?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Pourquoi_ne_pas_mettre_des_agrumes_dans_le_compost\"><\/span>Pourquoi ne pas mettre des agrumes dans le compost ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>L&rsquo;acidit\u00e9 C&rsquo;est la cause la plus souvent invoqu\u00e9e pour <b>ne pas composter<\/b> les <b>agrumes<\/b>. Tomates, ananas, kiwi, pommes sont aussi acides que les <b>agrumes<\/b>, mais <b>ne<\/b> sont pourtant <b>pas<\/b> interdits de <b>compostage<\/b>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_utiliser_les_epluchures_dorange\"><\/span><strong>Comment utiliser les \u00e9pluchures d&rsquo;orange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Utilisez la pelure fra\u00eeche d&rsquo;une <b>orange<\/b> pour frotter le bac \u00e0 \u00e9vier ou le lavabo. Faites mariner les pelures dans du vinaigre blanc pendant une semaine, puis filtrez. Versez le m\u00e9lange dans un vaporisateur et vous obtenez un nettoyant naturellement d\u00e9sinfectant, anti-calcaire et frais!<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_conserver_la_peau_dorange\"><\/span><strong>Comment conserver la peau d&rsquo;orange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Entaillez la <b>peau<\/b> avec un couteau entre les deux \u00ab\u00a0p\u00f4les\u00a0\u00bb de plusieurs stries. Les s\u00e8cher et les mettre \u00e0 plat dans une assiette dans un endroit sec et bien a\u00e9r\u00e9. Ils seront secs en environ une semaine. Conservez-les ensuite dans un bocal ou dans un sachet au cong\u00e9lateur.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ou_jeter_les_epluchures_dorange\"><\/span><strong>O\u00f9 jeter les \u00e9pluchures d&rsquo;orange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ajouter les pelures au compost<\/p>\n<p> Les \u00e9corces d&rsquo;agrumes peuvent \u00e9galement alimenter votre compost ! Il est toutefois pr\u00e9f\u00e9rable de les couper en petits morceaux pour faciliter leur d\u00e9composition.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quest-ce_qui_va_dans_le_compost\"><\/span><strong>Qu&rsquo;est-ce qui va dans le compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Voici une liste de ce <b>  qu <\/b> &lsquo;on peut mettre dans son <b>  compost <\/b> . <br \/> &#8230; <br \/> <b>  <b>   Composter  <\/b>  les mati\u00e8res vertes, molles et humides (riches en azote) <\/b> <\/p>\n<ul>\n<li>   \u00c9pluchures et d\u00e9chets de fruits et l\u00e9gumes. &#8230;  <\/li>\n<li>   Marc de caf\u00e9 avec le filtre en papier. &#8230;  <\/li>\n<li>   Sachets et feuilles de th\u00e9. &#8230;  <\/li>\n<li>   Fleurs fan\u00e9es.  <\/li>\n<li>   Tontes de gazon. &#8230;  <\/li>\n<li>   V\u00e9g\u00e9taux frais (feuilles, plantes de jardin, etc.).  <\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Comment_reussir_son_compost_les_erreurs_a_eviter\"><\/span><strong>Comment r\u00e9ussir son compost les erreurs \u00e0 \u00e9viter ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il est important de maintenir un certain taux d&rsquo;humidit\u00e9 pour bien entretenir <b>son compost<\/b>. Pensez \u00e0 l&rsquo;arroser de fa\u00e7on mod\u00e9r\u00e9e pour <b>\u00e9viter<\/b> qu&rsquo;il ne soit trop sec. Il est \u00e9galement important de remuer et m\u00e9langer votre tas de <b>compost<\/b> pour que celui-ci puisse bien fermenter. Enfin, optez pour un bac \u00e0 <b>compost<\/b> ferm\u00e9.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Est-ce_que_le_citron_va_au_compost\"><\/span><strong>Est-ce que le citron va au compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Sauvons les agrumes de la poubelle ! En effet, lors de la mise en place d&rsquo;un site de <b>compostage<\/b>, il <b>est<\/b> souvent stipul\u00e9 qu&rsquo;il <b>est<\/b> pr\u00e9f\u00e9rable de ne pas y d\u00e9poser des agrumes, sous peine de ne pas obtenir un \u00ab bon \u00bb <b>compost<\/b>. &#8230;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quel_dechet_pour_un_bon_compost\"><\/span><strong>Quel d\u00e9chet pour un bon compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les <b>d\u00e9chets<\/b> de cuisine : \u00e9pluchures, l\u00e9gumes et fruits ab\u00eem\u00e9s (crus ou cuits), coquilles d&rsquo;\u0153uf ou d&rsquo;hu\u00eetre broy\u00e9es en poudre, th\u00e9, marc de caf\u00e9. Et en petite quantit\u00e9 : restes de repas d&rsquo;origine v\u00e9g\u00e9tale (p\u00e2tes, riz, pur\u00e9e\u2026) sans sauce, pain sec bien \u00e9miett\u00e9.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pourquoi_pas_de_pain_dans_le_compost\"><\/span><strong>Pourquoi pas de pain dans le compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Tous les d\u00e9chets organiques sont compostables. Mais il peut y avoir des soucis avec le <b>pain<\/b>&#8230; En effet, si des moisissures vertes ou noires se sont d\u00e9velopp\u00e9es, celle-ci peuvent \u00eatre anti-bact\u00e9rienne et donc le <b>pain<\/b> se d\u00e9composera beaucoup moins vite.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Est-ce_quon_peut_mettre_du_pain_dans_le_compost\"><\/span><strong>Est-ce qu&rsquo;on peut mettre du pain dans le compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><b>Pain<\/b>. On l&rsquo;humidifie bien avant de le <b>mettre<\/b> au <b>compost<\/b> et on \u00e9vite d&rsquo;en <b>mettre<\/b> en trop grande quantit\u00e9. Plut\u00f4t <b>que<\/b> de <b>mettre<\/b> son <b>pain<\/b> rassis au <b>compost<\/b>, on <b>peut<\/b> en faire de la chapelure, du <b>pain<\/b> perdu\u2026 Plantes malades.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_faire_secher_peau_dorange\"><\/span><strong>Comment faire s\u00e9cher peau d&rsquo;orange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Retirer la partie <b>orange<\/b> de l&rsquo;\u00e9corce, sans pr\u00e9lever la partie blanche qui apportera trop d&rsquo;amertume. 3. D\u00e9posez une feuille de papier sulfuris\u00e9 sur votre plaque pour le four. \u00c9parpillez les \u00e9corces sur la plaque et enfournez pour environ 1h20 de s\u00e9chage.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_secher_la_peau_dorange\"><\/span><strong>Comment s\u00e9cher la peau d&rsquo;orange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u2013 Au four pr\u00e9chauff\u00e9 \u00e0 75\u00baC, d\u00e9poser les zestes en les \u00e9talant bien sur une plaque de four recouverte de papier de cuisson. Laisser <b>s\u00e9cher<\/b> les zestes pendant 2 heures. Ouvrir la porte du four et renouveler l&rsquo;op\u00e9ration pour 1 ou 2 heures en baissant \u00e0 50\u00baC.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_faire_secher_la_peau_dorange\"><\/span><strong>Comment faire s\u00e9cher la peau d&rsquo;orange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Vous n&rsquo;avez qu&rsquo;\u00e0 faire <b>s\u00e9cher<\/b> vos \u00e9corces d&rsquo;agrumes \u00e0 l&rsquo;air libre pendant 24 heures ou au four \u00e0 basse temp\u00e9rature avant de les mettre dans des vieux bas ou collants que vous nouerez. Eh hop, pas besoin de couture, le tour est jou\u00e9, vous avez de quoi parfumer vos armoires d&rsquo;une odeur rafra\u00eechissante.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_faire_secher_la_peau_dorange-2\"><\/span><strong>Comment faire s\u00e9cher la peau d&rsquo;orange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Retirer la partie <b>orange<\/b> de l&rsquo;<b>\u00e9corce<\/b>, sans pr\u00e9lever la partie blanche qui apportera trop d&rsquo;amertume. 3. D\u00e9posez une feuille de papier sulfuris\u00e9 sur votre plaque pour le four. \u00c9parpillez les <b>\u00e9corces<\/b> sur la plaque et enfournez pour environ 1h20 de s\u00e9chage.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Est-ce_que_la_peau_dune_orange_se_mange\"><\/span><strong>Est-ce que la peau d&rsquo;une orange se mange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les \u00e9pluchures d&rsquo;<b>orange<\/b> prot\u00e8gent le corps les inflammations et les maladies cardiaques. Pas besoin de croquer directement dans la <b>peau<\/b>, rappez les zestes dans vos plats. En r\u00e9alit\u00e9 nous mangeons les racines de cette plante, mais au d\u00e9but <b>elle<\/b> \u00e9tait cultiv\u00e9e pour ses feuilles vertes.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_secher_la_peau_dorange-2\"><\/span><strong>Comment s\u00e9cher la peau d&rsquo;orange ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Retirer la partie <b>orange<\/b> de l&rsquo;\u00e9corce, sans pr\u00e9lever la partie blanche qui apportera trop d&rsquo;amertume. 3. D\u00e9posez une feuille de papier sulfuris\u00e9 sur votre plaque pour le four. \u00c9parpillez les \u00e9corces sur la plaque et enfournez pour environ 1h20 de s\u00e9chage.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pourquoi_il_ne_faut_pas_mettre_dagrumes_dans_un_compost\"><\/span><strong>Pourquoi il ne faut pas mettre d&rsquo;agrumes dans un compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>L&rsquo;acidit\u00e9 C&rsquo;est la cause la plus souvent invoqu\u00e9e pour ne <b>pas composter<\/b> les <b>agrumes<\/b>. Tomates, ananas, kiwi, pommes sont aussi acides que les <b>agrumes<\/b>, mais ne sont pourtant <b>pas<\/b> interdits de <b>compostage<\/b>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pourquoi_pas_de_pelures_dagrumes_dans_le_compost\"><\/span><strong>Pourquoi pas de pelures d&rsquo;agrumes dans le compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>les <b>peaux d&rsquo;agrumes<\/b> mettent du temps \u00e0 se d\u00e9composer car leur \u00e9piderme est couvert d&rsquo;une cire, qui constitue une \u00ab barri\u00e8re \u00e0 bact\u00e9ries \u00bb ; les <b>agrumes<\/b> sont acides et leur apport risque d&rsquo;acidifier le <b>compost<\/b> ; les <b>agrumes<\/b> peuvent \u00eatre fortement trait\u00e9s et cela peut nuire aux micro-organismes pr\u00e9sents dans le <b>compost<\/b>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Est-ce_que_la_viande_va_au_compost\"><\/span><strong>Est-ce que la viande va au compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La <b>viande<\/b> et le poisson ont besoin d&rsquo;une temp\u00e9rature \u00e9lev\u00e9e, que l&rsquo;on ne rencontre pas dans un <b>compost<\/b> individuel, pour se d\u00e9composer. Par ailleurs, ces aliments risquent d&rsquo;attirer des animaux. &#8230; Les produits laitiers attirent les animaux et parasites, mais peuvent \u00e9galement \u00e9touffer le <b>compost<\/b>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quest-ce_qui_va_dans_le_bac_brun\"><\/span><strong>Qu&rsquo;est-ce qui va dans le bac brun ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>   R\u00c9SIDUS. DE CUISINE. \u2022 Fruits et l\u00e9gumes. \u2022 Pain, p\u00e2tes et produits c\u00e9r\u00e9aliers. \u2022 G\u00e2teaux et sucreries. &#8230;  <\/li>\n<li>   R\u00c9SIDUS DE JARDIN. \u2022 Feuilles mortes, gazon et. r\u00e9sidus de plates-bandes. \u2022 Fleurs, plantes, sable et terre. &#8230;  <\/li>\n<li>   AUTRES. MATI\u00c8RES. ACCEPT\u00c9ES. \u2022 Papiers et cartons souill\u00e9s. &#8230;  <\/li>\n<li>   j&#8217;embarque. Notez   <b>    que   <\/b>   . les sacs de. plastique.  <\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Est-ce_que_les_noyaux_vont_au_compost\"><\/span><strong>Est-ce que les noyaux vont au compost ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les coques et les <b>noyaux<\/b> sont constitu\u00e9s de bois souvent durs ; de ce fait, ils ne se d\u00e9composent que tr\u00e8s lentement. Cependant, leur pr\u00e9sence peut am\u00e9liorer l&rsquo;a\u00e9ration et le drainage du <b>compost<\/b>.<\/p>\n<hr \/>\n<p><em>Editeurs: 5 &#8211; R\u00e9f\u00e9rences: 23 articles<\/em><\/p>\n<p><em>N\u2019oubliez pas de partager l\u2019article !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le charbon de barbecue comme les m\u00e9gots de cigarettes, la poussi\u00e8re d&rsquo;aspirateur, les mat\u00e9riaux non biod\u00e9gradables, des d\u00e9chets d&rsquo;animaux, les graines et noyaux, les feuilles verniss\u00e9es (lierre, laurier), les lisserons et plantes rampantes, les plantes et v\u00e9g\u00e9taux trait\u00e9s r\u00e9sineux, ne peuvent pas \u00eatre mis dans le &#8230; Mais encore, Comment utiliser les pelures d&rsquo;agrumes ? [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3457],"tags":[],"class_list":["post-47169","post","type-post","status-publish","format-standard","hentry","category-maison"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v25.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ?<\/title>\n<meta name=\"description\" content=\"Le charbon de barbecue comme les m\u00e9gots de cigarettes, la poussi\u00e8re d&#039;aspirateur, les mat\u00e9riaux non biod\u00e9gradables, des d\u00e9chets d&#039;animaux, les graines et\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ? - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\" \/>\n<meta property=\"og:description\" content=\"Le charbon de barbecue comme les m\u00e9gots de cigarettes, la poussi\u00e8re d&#039;aspirateur, les mat\u00e9riaux non biod\u00e9gradables, des d\u00e9chets d&#039;animaux, les graines et\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/flashmode.magazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-23T03:20:32+00:00\" \/>\n<meta name=\"author\" content=\"Nora D.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@agenceflashmode\" \/>\n<meta name=\"twitter:site\" content=\"@agenceflashmode\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nora D.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/\",\"url\":\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/\",\"name\":\"Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ?\",\"isPartOf\":{\"@id\":\"https:\/\/flashmode.tn\/magazine\/#website\"},\"datePublished\":\"2021-11-23T03:20:32+00:00\",\"author\":{\"@id\":\"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/ebeaf8414935b60ba8817ab0babd7fbe\"},\"description\":\"Le charbon de barbecue comme les m\u00e9gots de cigarettes, la poussi\u00e8re d'aspirateur, les mat\u00e9riaux non biod\u00e9gradables, des d\u00e9chets d'animaux, les graines et\",\"breadcrumb\":{\"@id\":\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/flashmode.tn\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/#website\",\"url\":\"https:\/\/flashmode.tn\/magazine\/\",\"name\":\"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\",\"description\":\"Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb, cr\u00e9\u00e9 pour les hommes et les femmes : conseils beaut\u00e9, mode femme, mode homme, recettes de cuisine, c\u00e9l\u00e9brit\u00e9s et people, mannequins et top modeles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flashmode.tn\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/ebeaf8414935b60ba8817ab0babd7fbe\",\"name\":\"Nora D.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a51d897ddf0a2216affe16e03a39790850922d1b5b29f147f35db7ccb8861eab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a51d897ddf0a2216affe16e03a39790850922d1b5b29f147f35db7ccb8861eab?s=96&d=mm&r=g\",\"caption\":\"Nora D.\"},\"url\":\"https:\/\/flashmode.tn\/magazine\/author\/nora-damak\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ?","description":"Le charbon de barbecue comme les m\u00e9gots de cigarettes, la poussi\u00e8re d'aspirateur, les mat\u00e9riaux non biod\u00e9gradables, des d\u00e9chets d'animaux, les graines et","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/","og_locale":"fr_FR","og_type":"article","og_title":"Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ? - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","og_description":"Le charbon de barbecue comme les m\u00e9gots de cigarettes, la poussi\u00e8re d'aspirateur, les mat\u00e9riaux non biod\u00e9gradables, des d\u00e9chets d'animaux, les graines et","og_url":"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/","og_site_name":"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","article_publisher":"https:\/\/www.facebook.com\/flashmode.magazine\/","article_published_time":"2021-11-23T03:20:32+00:00","author":"Nora D.","twitter_card":"summary_large_image","twitter_creator":"@agenceflashmode","twitter_site":"@agenceflashmode","twitter_misc":{"\u00c9crit par":"Nora D.","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/","url":"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/","name":"Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ?","isPartOf":{"@id":"https:\/\/flashmode.tn\/magazine\/#website"},"datePublished":"2021-11-23T03:20:32+00:00","author":{"@id":"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/ebeaf8414935b60ba8817ab0babd7fbe"},"description":"Le charbon de barbecue comme les m\u00e9gots de cigarettes, la poussi\u00e8re d'aspirateur, les mat\u00e9riaux non biod\u00e9gradables, des d\u00e9chets d'animaux, les graines et","breadcrumb":{"@id":"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/flashmode.tn\/magazine\/quels-sont-les-dechets-a-ne-pas-mettre-dans-le-compost-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/flashmode.tn\/magazine\/"},{"@type":"ListItem","position":2,"name":"Quels sont les d\u00e9chets \u00e0 ne pas mettre dans le compost ?"}]},{"@type":"WebSite","@id":"https:\/\/flashmode.tn\/magazine\/#website","url":"https:\/\/flashmode.tn\/magazine\/","name":"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","description":"Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb, cr\u00e9\u00e9 pour les hommes et les femmes : conseils beaut\u00e9, mode femme, mode homme, recettes de cuisine, c\u00e9l\u00e9brit\u00e9s et people, mannequins et top modeles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flashmode.tn\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/ebeaf8414935b60ba8817ab0babd7fbe","name":"Nora D.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a51d897ddf0a2216affe16e03a39790850922d1b5b29f147f35db7ccb8861eab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a51d897ddf0a2216affe16e03a39790850922d1b5b29f147f35db7ccb8861eab?s=96&d=mm&r=g","caption":"Nora D."},"url":"https:\/\/flashmode.tn\/magazine\/author\/nora-damak\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8BPGr-cgN","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/posts\/47169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/comments?post=47169"}],"version-history":[{"count":0,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/posts\/47169\/revisions"}],"wp:attachment":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/media?parent=47169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/categories?post=47169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/tags?post=47169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}