{"id":88539,"date":"2022-06-09T18:06:15","date_gmt":"2022-06-09T16:06:15","guid":{"rendered":"https:\/\/flashmode.tn\/magazine\/?p=88539"},"modified":"2022-06-09T18:06:15","modified_gmt":"2022-06-09T16:06:15","slug":"comment-faire-quand-un-mac-a-pris-leau","status":"publish","type":"post","link":"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/","title":{"rendered":"Comment faire quand un Mac a pris l&rsquo;eau ?"},"content":{"rendered":"<p>Si votre ordinateur <b>Macbook<\/b> Air ou <b>Macbook<\/b> Pro a <b>pris l&rsquo;eau<\/b>, \u00e9teignez le dans les secondes qui suivent. Pour se <b>faire<\/b>, vous pouvez soit maintenir le bouton d&rsquo;alimentation (Power) enfonc\u00e9, soit l&rsquo;\u00e9teindre en passant par le menu Pomme (la petite pomme noire situ\u00e9e en haut \u00e0 gauche de votre \u00e9cran).<\/p>\n<p>De plus, Comment faire s\u00e9cher un Mac ? Quelques techniques pour <b>s\u00e9cher<\/b> le <b>Mac<\/b><\/p>\n<p> refermer le carton ; laisser l&rsquo;ordinateur <b>s\u00e9cher<\/b> pendant 48 heures. Il est \u00e9galement possible de d\u00e9connecter la batterie et la placer dans un carton herm\u00e9tique tapiss\u00e9 de riz ou de recouvrir le clavier de riz (\u00e0 condition que les touches soient tr\u00e8s proches les unes des autres).<\/p>\n<p>Comment sauver un ordinateur qui a pris leau ?<\/p>\n<p><b>  J&rsquo;ai renvers\u00e9 de l&rsquo;  <b>   eau  <\/b>  sur mon PC portable. <\/b> <b>  Que faire ? <\/b> <\/p>\n<ol>\n<li>   \u00c9teignez imm\u00e9diatement votre PC. La premi\u00e8re chose \u00e0 faire est d&rsquo;\u00e9teindre puis de d\u00e9brancher votre PC s&rsquo;il est reli\u00e9 \u00e0 un c\u00e2ble d&rsquo;alimentation. &#8230;  <\/li>\n<li>   Retirez la batterie. &#8230;  <\/li>\n<li>   Retournez votre PC pour \u00e9vacuer le liquide. &#8230;  <\/li>\n<li>   Laissez s\u00e9cher votre PC pendant 24 heures.  <\/li>\n<\/ol>\n<p>Par ailleurs, Comment enlever l&rsquo;eau de son ordi ? En g\u00e9n\u00e9ral, c&rsquo;est plut\u00f4t le clavier sur lequel se trouve renvers\u00e9 un liquide. Dans ce cas, \u00e9talez le papier absorbant sur toute sa surface. Veillez \u00e0 le passer entre les touches si cela est possible. L&rsquo;utilisation d&rsquo;un s\u00e8che-cheveux, en conservant une distance et une chaleur raisonnables, peut aussi s&rsquo;av\u00e9rer utile.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenus de la page<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#Comment_ouvrir_un_ordinateur_Mac\" >Comment ouvrir un ordinateur Mac ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#Comment_deverrouiller_son_Mac_sans_mot_de_passe\" >Comment d\u00e9verrouiller son Mac sans mot de passe ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#Comment_allumer_le_MacBook_Pro\" >Comment allumer le MacBook Pro ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#Comment_trouver_mot_de_passe_sur_Mac\" >Comment trouver mot de passe sur Mac ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#Comment_verifier_la_garantie_Samsung\" >Comment v\u00e9rifier la garantie Samsung ?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#Quelle_est_la_duree_de_garantie_legale_en_France\" >Quelle est la dur\u00e9e de garantie l\u00e9gale en France ?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Comment_ouvrir_un_ordinateur_Mac\"><\/span>Comment ouvrir un ordinateur Mac ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Poser une ventouse sur le coin sup\u00e9rieur gauche de la vitre, puis une deuxi\u00e8me sur le coin sup\u00e9rieur droit. Tirez sur les deux ventouses. Vous n&rsquo;avez pas besoin de forcer excessivement, la vitre \u00e9tant simplement maintenue par des aimants. Entreposez-la en lieu s\u00fbr, \u00e9videmment prot\u00e9g\u00e9e de la poussi\u00e8re.<\/p>\n<p>O\u00f9 trouver la garantie Apple ? Connectez-vous avec votre identifiant <b>  Apple <\/b> , puis choisissez votre appareil. <br \/> &#8230; <br \/> <b>  V\u00e9rifier si votre appareil est couvert par un contrat AppleCare ou une  <b>   garantie  <\/b>  limit\u00e9e  <b>   Apple  <\/b> <\/b> <\/p>\n<ul>\n<li>   Allez \u00e0 la page checkcoverage.   <b>    apple   <\/b>   .com\/fr\/fr\/.  <\/li>\n<li>   Saisissez le num\u00e9ro de s\u00e9rie de l&rsquo;appareil.  <\/li>\n<li>   Suivez les instructions \u00e0 l&rsquo;\u00e9cran.  <\/li>\n<\/ul>\n<p>Comment on allume un Mac ? <b>Allumer<\/b> son <b>iMac<\/b><\/p>\n<p>  Localisez le bouton d&rsquo;alimentation qui se trouve \u00e0 l&rsquo;arri\u00e8re de votre <b>iMac<\/b> dans le coin inf\u00e9rieur droit, lorsque vous regardez l&rsquo;avant de votre <b>iMac<\/b>, placez votre doigt sur la main gauche \u00e0 l&rsquo;arri\u00e8re de votre ordinateur. C&rsquo;est un bouton rond avec l&rsquo;ic\u00f4ne alimentation.<\/p>\n<p>Comment ouvrir une session Mac sans avoir le mot de passe ? Acc\u00e9dez au menu Pomme \uf8ff &gt; Pr\u00e9f\u00e9rences Syst\u00e8me, puis cliquez sur S\u00e9curit\u00e9 et confidentialit\u00e9. Dans le volet G\u00e9n\u00e9ral, d\u00e9s\u00e9lectionnez \u00ab Exiger un <b>mot de passe<\/b> apr\u00e8s la suspension d&rsquo;activit\u00e9 ou le lancement de l&rsquo;\u00e9conomiseur d&rsquo;\u00e9cran \u00bb.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_deverrouiller_son_Mac_sans_mot_de_passe\"><\/span>Comment d\u00e9verrouiller son Mac sans mot de passe ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><b>  Voici  <b>   comment  <\/b>  vous y prendre : <\/b> <\/p>\n<ol>\n<li>   \u00c9teignez votre ordinateur.  <\/li>\n<li>   D\u00e9marrez en mode R\u00e9cup\u00e9ration en maintenant appuy\u00e9 Command + R et D\u00e9marrer (soyez patient cela peut \u00eatre un peu lent).  <\/li>\n<li>   D\u00e8s que la barre de charge appara\u00eet, rel\u00e2chez les touches.  <\/li>\n<li>   S\u00e9lectionnez Utilitaire de disque, puis appuyez sur Continuer.  <\/li>\n<\/ol>\n<p>Comment voir la garantie ? Consulter la facture d&rsquo;achat d&rsquo;un smartphone pour conna\u00eetre la fin de la <b>garantie<\/b>. La mani\u00e8re la plus simple et la plus rapide pour d\u00e9couvrir la date de fin de <b>garantie<\/b> de n&rsquo;importe quel smartphone est de se pencher sur la facture. D\u00e9livr\u00e9e lors de l&rsquo;achat, la facture contient la date de fin de <b>garantie<\/b> du t\u00e9l\u00e9phone.<\/p>\n<p>Quelle est la garantie d&rsquo;un iPhone ?<\/p>\n<p>La <b>garantie<\/b> limit\u00e9e Apple couvre votre <b>iPhone<\/b> et vos accessoires Apple contre les d\u00e9fauts de fabrication pendant un an \u00e0 compter de la date d&rsquo;achat de votre produit. Elle vient s&rsquo;ajouter aux droits pr\u00e9vus par la loi sur la protection des consommateurs.<\/p>\n<p>Comment faire marcher la garantie d&rsquo;Apple ? Avant de pouvoir b\u00e9n\u00e9ficier du service de <b>garantie<\/b>, <b>Apple<\/b> ou ses repr\u00e9sentants peuvent vous demander de fournir une preuve d&rsquo;achat, de r\u00e9pondre \u00e0 des questions dans le but de les assister \u00e0 diagnostiquer les probl\u00e8mes potentiels ou de suivre les proc\u00e9dures d&rsquo;<b>Apple<\/b> pour obtenir le service de <b>garantie<\/b>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_allumer_le_MacBook_Pro\"><\/span>Comment allumer le MacBook Pro ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Utilisez Touch ID (bouton d&rsquo;alimentation).<\/p>\n<p> Appuyez pour <b>allumer<\/b> votre <b>MacBook Pro<\/b> (ou soulevez simplement l&rsquo;\u00e9cran et appuyez sur n&rsquo;importe quelle touche). La premi\u00e8re fois que vous d\u00e9marrez ou red\u00e9marrez l&rsquo;ordinateur, vous devez vous connecter en saisissant votre mot de passe.<\/p>\n<p>Comment allumer un imac sans le bouton Power ?<\/p>\n<p>le fameux raccourcis des touches CTRL, ALT &amp; SUPPR. En effet, il vous suffira de maintenir ces touches enfonc\u00e9es en m\u00eame temps afin que votre ordinateur Macbook Pro ou Macbook Air red\u00e9marre.<\/p>\n<p>Comment allumer un Mac \u00e9cran noir ? Appuyez sur le bouton d&rsquo;alimentation, rel\u00e2chez-le, puis appuyez imm\u00e9diatement sur les touches Commande (\u2318) + R et maintenez-les enfonc\u00e9es jusqu&rsquo;\u00e0 ce qu&rsquo;un logo Apple ou une autre image s&rsquo;affiche. Si l&rsquo;<b>\u00e9cran<\/b> est toujours vide au bout d&rsquo;environ 20 secondes, contactez l&rsquo;assistance Apple.<\/p>\n<p>Comment r\u00e9cup\u00e9rer le mot de passe administrateur Mac ? R\u00e9initialiser le <b>mot de passe<\/b> avec un compte iCloud<\/p>\n<p> Rendez-vous dans la section Utilisateurs et groupes des Pr\u00e9f\u00e9rences Syst\u00e8me, s\u00e9lectionnez votre compte dans la barre lat\u00e9rale, et v\u00e9rifiez que l&rsquo;option Autoriser la r\u00e9initialisation du <b>mot de passe<\/b> avec l&rsquo;identifiant Apple est coch\u00e9e.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_trouver_mot_de_passe_sur_Mac\"><\/span>Comment trouver mot de passe sur Mac ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><b>  Afficher les  <b>   mots de passe  <\/b>  enregistr\u00e9s dans Safari <\/b> <\/p>\n<ol>\n<li>   Ouvrez Safari.  <\/li>\n<li>   Dans le menu Safari, choisissez Pr\u00e9f\u00e9rences, puis cliquez sur   <b>    Mots de passe   <\/b>   .  <\/li>\n<li>   Connectez-vous avec Touch ID ou entrez   <b>    le mot de passe   <\/b>   de votre compte utilisateur. &#8230;  <\/li>\n<li>   S\u00e9lectionnez un site web, puis cliquez sur Modifier.  <\/li>\n<\/ol>\n<p>Comment d\u00e9bloquer Macbook Air ? R\u00e9installez votre MacOs en utilisant le Mode de R\u00e9cup\u00e9ration<\/p>\n<p> Allumez ou red\u00e9marrez votre <b>Mac<\/b>. D\u00e8s le d\u00e9but du d\u00e9marrage, appuyez et maintenez la touche Commande et la touche R. Rel\u00e2chez les touches une fois que vous voyez le logo <b>Apple<\/b> apparaitre. Ensuite, vous verrez plusieurs outils pour r\u00e9parer votre ordinateur.<\/p>\n<p>Comment d\u00e9bloquer un ordinateur Apple ?<\/p>\n<p>Tout d&rsquo;abord, ouvrez le menu <b>Apple<\/b> en haut \u00e0 gauche de l&rsquo;\u00e9cran, puis s\u00e9lectionnez \u00ab Red\u00e9marrer \u00bb. Si la souris ne r\u00e9pond pas et que vous ne pouvez cliquer sur rien du tout, alors vous pouvez appuyer sur les touches Command + Control + Eject pour red\u00e9marrer directement votre <b>Mac<\/b>.<\/p>\n<p>Comment retrouver nom d&rsquo;utilisateur et mot de passe Mac ? <b>  Voici  <b>   comment  <\/b>  proc\u00e9der : <\/b> <\/p>\n<ol>\n<li>   Red\u00e9marrez votre   <b>    Mac   <\/b>   . \u2026  <\/li>\n<li>   Pendant le red\u00e9marrage, maintenez enfonc\u00e9es les touches Commande + R jusqu&rsquo;\u00e0 ce que vous voyiez le logo Apple. \u2026  <\/li>\n<li>   Allez dans le menu Apple en haut et cliquez sur Utilitaires. \u2026  <\/li>\n<li>   Cliquez ensuite sur Terminal.  <\/li>\n<li>   Tapez \u00ab resetpassword \u00bb dans la fen\u00eatre du terminal. \u2026  <\/li>\n<\/ol>\n<h3><span class=\"ez-toc-section\" id=\"Comment_verifier_la_garantie_Samsung\"><\/span>Comment v\u00e9rifier la garantie Samsung ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Tout client ayant achet\u00e9 un t\u00e9l\u00e9phone authentique <b>Samsung<\/b> pourra b\u00e9n\u00e9ficier d&rsquo;une <b>garantie<\/b> de 24 mois aupr\u00e8s de nos Services Apres Vente. <b>SAMSUNG<\/b> vous invite \u00e0 <b>v\u00e9rifier<\/b> l&rsquo;authenticit\u00e9 de votre t\u00e9l\u00e9phone \u00e0 l&rsquo;achat puis l&rsquo;enregistrer par SMS : <b>VERIFIER<\/b> : (<b>V\u00e9rifier<\/b>*num\u00e9ro IMEI # au 22023).<\/p>\n<p>Comment savoir si son t\u00e9l\u00e9phone est encore sous garantie ? En g\u00e9n\u00e9ral, ce sont les petites lignes \u00e9crites en bas de votre facture ou dans <b>le<\/b> livret inclus dans la bo\u00eete du <b>smartphone<\/b> (que peu de gens lisent, h\u00e9las).<\/p>\n<p>Qu&rsquo;est-ce Que couvre la garantie Apple ?<\/p>\n<p>La <b>garantie Apple<\/b> pour iPhone, iPad et Mac <b>est<\/b> une <b>garantie<\/b> l\u00e9gale du fabricant d&rsquo;un an <b>qui<\/b> garantit la conformit\u00e9 des produits et les vices cach\u00e9s. <b>Apple<\/b> garantit ainsi tous les d\u00e9fauts de conformit\u00e9 de ses appareils, \u00e0 savoir : &#8211; le mat\u00e9riel ; &#8211; les accessoires.<\/p>\n<p>Comment faire marcher la garantie iPhone ? Une pi\u00e8ce ou un produit de remplacement ou un Produit Apple r\u00e9par\u00e9 est <b>garanti<\/b> pendant le reste de la p\u00e9riode de la <b>garantie<\/b> du Produit Apple d&rsquo;origine ou pendant quatre-vingt-dix (90) jours \u00e0 compter de la date de remplacement ou de r\u00e9paration, la couverture la plus longue \u00e9tant prise en compte.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quelle_est_la_duree_de_garantie_legale_en_France\"><\/span>Quelle est la dur\u00e9e de garantie l\u00e9gale en France ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il existe pour cela une <b>garantie l\u00e9gale<\/b> de conformit\u00e9. Cette <b>garantie<\/b> s&rsquo;applique aux d\u00e9fauts d\u00e9j\u00e0 pr\u00e9sents \u00e0 la date de livraison. Elle s&rsquo;applique 2 ans maximum apr\u00e8s la livraison d&rsquo;un bien neuf et 1 an pour un bien d&rsquo;occasion.<\/p>\n<p>Quand s&rsquo;active la garantie Apple ?<\/p>\n<p>Pas de panique : si tu as achet\u00e9 ta montre neuve en magasin <b>Apple<\/b> Store ou aupr\u00e8s d&rsquo;un revendeur agr\u00e9\u00e9 <b>Apple<\/b>, ta <b>garantie<\/b> a commenc\u00e9 le jour de cette vente\/achat. Donc disons le 1er octobre 2017 = \u00e7a veut dire que tu as 1 an de constructeur de <b>garantie Apple<\/b> jusqu&rsquo;au 1er octobre 2018. Qu&rsquo;est-ce que la garantie Apple Care ?<\/p>\n<p>L&rsquo;AppleCare+ garantit la r\u00e9paration ou le remplacement de votre iPhone pour deux incidents relevant de dommages accidentels par p\u00e9riode de douze mois, chacun d&rsquo;eux \u00e9tant soumis \u00e0 des frais suppl\u00e9mentaires (de 29 \u20ac pour les d\u00e9g\u00e2ts affectant l&rsquo;\u00e9cran ou le dos en verre et de 99 \u20ac pour tout autre type de d\u00e9g\u00e2ts), et couvre &#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si votre ordinateur Macbook Air ou Macbook Pro a pris l&rsquo;eau, \u00e9teignez le dans les secondes qui suivent. Pour se faire, vous pouvez soit maintenir le bouton d&rsquo;alimentation (Power) enfonc\u00e9, soit l&rsquo;\u00e9teindre en passant par le menu Pomme (la petite pomme noire situ\u00e9e en haut \u00e0 gauche de votre \u00e9cran). De plus, Comment faire s\u00e9cher [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[80],"tags":[],"class_list":["post-88539","post","type-post","status-publish","format-standard","hentry","category-lifestyle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.0 (Yoast SEO v25.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment faire quand un Mac a pris l&#039;eau ? - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb<\/title>\n<meta name=\"description\" content=\"Si votre ordinateur Macbook Air ou Macbook Pro a pris l&#039;eau, \u00e9teignez le dans les secondes qui suivent. Pour se faire, vous pouvez soit maintenir le\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment faire quand un Mac a pris l&#039;eau ? - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\" \/>\n<meta property=\"og:description\" content=\"Si votre ordinateur Macbook Air ou Macbook Pro a pris l&#039;eau, \u00e9teignez le dans les secondes qui suivent. Pour se faire, vous pouvez soit maintenir le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/\" \/>\n<meta property=\"og:site_name\" content=\"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/flashmode.magazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T16:06:15+00:00\" \/>\n<meta name=\"author\" content=\"PeopleLife\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@agenceflashmode\" \/>\n<meta name=\"twitter:site\" content=\"@agenceflashmode\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"PeopleLife\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/\",\"url\":\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/\",\"name\":\"Comment faire quand un Mac a pris l'eau ? - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\",\"isPartOf\":{\"@id\":\"https:\/\/flashmode.tn\/magazine\/#website\"},\"datePublished\":\"2022-06-09T16:06:15+00:00\",\"author\":{\"@id\":\"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/6815bd30337e8756d5357219766efcc3\"},\"description\":\"Si votre ordinateur Macbook Air ou Macbook Pro a pris l'eau, \u00e9teignez le dans les secondes qui suivent. Pour se faire, vous pouvez soit maintenir le\",\"breadcrumb\":{\"@id\":\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/flashmode.tn\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment faire quand un Mac a pris l&rsquo;eau ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/#website\",\"url\":\"https:\/\/flashmode.tn\/magazine\/\",\"name\":\"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb\",\"description\":\"Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb, cr\u00e9\u00e9 pour les hommes et les femmes : conseils beaut\u00e9, mode femme, mode homme, recettes de cuisine, c\u00e9l\u00e9brit\u00e9s et people, mannequins et top modeles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flashmode.tn\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/6815bd30337e8756d5357219766efcc3\",\"name\":\"PeopleLife\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8098f49196034391d93ae20d939ad33b14f6b745c986049ad803a54f4113e18c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8098f49196034391d93ae20d939ad33b14f6b745c986049ad803a54f4113e18c?s=96&d=mm&r=g\",\"caption\":\"PeopleLife\"},\"url\":\"https:\/\/flashmode.tn\/magazine\/author\/peoplelife\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment faire quand un Mac a pris l'eau ? - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","description":"Si votre ordinateur Macbook Air ou Macbook Pro a pris l'eau, \u00e9teignez le dans les secondes qui suivent. Pour se faire, vous pouvez soit maintenir le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment faire quand un Mac a pris l'eau ? - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","og_description":"Si votre ordinateur Macbook Air ou Macbook Pro a pris l'eau, \u00e9teignez le dans les secondes qui suivent. Pour se faire, vous pouvez soit maintenir le","og_url":"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/","og_site_name":"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","article_publisher":"https:\/\/www.facebook.com\/flashmode.magazine\/","article_published_time":"2022-06-09T16:06:15+00:00","author":"PeopleLife","twitter_card":"summary_large_image","twitter_creator":"@agenceflashmode","twitter_site":"@agenceflashmode","twitter_misc":{"\u00c9crit par":"PeopleLife","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/","url":"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/","name":"Comment faire quand un Mac a pris l'eau ? - Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","isPartOf":{"@id":"https:\/\/flashmode.tn\/magazine\/#website"},"datePublished":"2022-06-09T16:06:15+00:00","author":{"@id":"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/6815bd30337e8756d5357219766efcc3"},"description":"Si votre ordinateur Macbook Air ou Macbook Pro a pris l'eau, \u00e9teignez le dans les secondes qui suivent. Pour se faire, vous pouvez soit maintenir le","breadcrumb":{"@id":"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/flashmode.tn\/magazine\/comment-faire-quand-un-mac-a-pris-leau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/flashmode.tn\/magazine\/"},{"@type":"ListItem","position":2,"name":"Comment faire quand un Mac a pris l&rsquo;eau ?"}]},{"@type":"WebSite","@id":"https:\/\/flashmode.tn\/magazine\/#website","url":"https:\/\/flashmode.tn\/magazine\/","name":"Flashmode Magazine | Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb","description":"Magazine de mode et style de vie Num\u00e9ro un en Tunisie et au Maghreb, cr\u00e9\u00e9 pour les hommes et les femmes : conseils beaut\u00e9, mode femme, mode homme, recettes de cuisine, c\u00e9l\u00e9brit\u00e9s et people, mannequins et top modeles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flashmode.tn\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/6815bd30337e8756d5357219766efcc3","name":"PeopleLife","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flashmode.tn\/magazine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8098f49196034391d93ae20d939ad33b14f6b745c986049ad803a54f4113e18c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8098f49196034391d93ae20d939ad33b14f6b745c986049ad803a54f4113e18c?s=96&d=mm&r=g","caption":"PeopleLife"},"url":"https:\/\/flashmode.tn\/magazine\/author\/peoplelife\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8BPGr-n23","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/posts\/88539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/comments?post=88539"}],"version-history":[{"count":0,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/posts\/88539\/revisions"}],"wp:attachment":[{"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/media?parent=88539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/categories?post=88539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flashmode.tn\/magazine\/wp-json\/wp\/v2\/tags?post=88539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}